{"id":15491,"date":"2026-02-18T10:36:20","date_gmt":"2026-02-18T10:36:20","guid":{"rendered":"https:\/\/greenpower.equipment\/?p=15491"},"modified":"2026-02-18T10:36:20","modified_gmt":"2026-02-18T10:36:20","slug":"modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur","status":"publish","type":"post","link":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/","title":{"rendered":"Modernisation de l&#8217;EKKO-2: d\u00e9veloppement de clapets d&#8217;air r\u00e9glables pour le foyer et le postcombusteur"},"content":{"rendered":"\n<p>GreenPower poursuit la modernisation du syst\u00e8me de contr\u00f4le automatique (SCA) du four de pyrolyse EKKO-2. L&#8217;objectif principal de la mise en \u0153uvre du SCA est de r\u00e9duire le niveau d&#8217;intervention du personnel dans l&#8217;exploitation du four, afin d&#8217;optimiser le processus de contr\u00f4le, de minimiser le facteur humain et d&#8217;accro\u00eetre la stabilit\u00e9 des processus de production.<\/p>\n\n\n\n<p>Dans le cadre des travaux mentionn\u00e9s ci-dessus, des clapets d\u2019air \u00e0 r\u00e9glage automatique ont \u00e9t\u00e9 d\u00e9velopp\u00e9s pour le foyer et le postcombusteur. Ils assurent un r\u00e9glage automatique et s\u00fbr de l\u2019apport d\u2019air vers le foyer et le postcombusteur du four, ce qui influence \u00e0 son tour l\u2019organisation du processus de combustion du gaz de pyrolyse dans le foyer ainsi que la postcombustion dans le postcombusteur.<\/p>\n\n\n\n<p>L\u2019objectif est d\u2019assurer un fonctionnement stable du four : absence de modes d\u2019urgence, r\u00e9duction des erreurs du personnel, ainsi que limitation des \u00e9missions nocives dans l\u2019atmosph\u00e8re (produits d\u2019une postcombustion incompl\u00e8te des gaz de pyrolyse).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"761\" src=\"https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193-1024x761.jpg\" alt=\"\" class=\"wp-image-15465\" style=\"object-fit:contain;width:400px;height:400px\" srcset=\"https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193-1024x761.jpg 1024w, https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193-300x223.jpg 300w, https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193-768x571.jpg 768w, https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>1. Pourquoi est-ce important ?<br><\/strong>&nbsp;<strong>a.<\/strong> Le contr\u00f4le de l&#8217;apport d&#8217;air de combustion dans le foyer et le postcombusteur est essentiel pour un fonctionnement s\u00fbr et efficace : l&#8217;exc\u00e8s comme le manque d&#8217;air r\u00e9duisent l&#8217;efficacit\u00e9 et peuvent entra\u00eener des r\u00e9gimes instables.<br>&nbsp;<strong>b.<\/strong> Le contr\u00f4le de la temp\u00e9rature dans le foyer, dans une plage de 900 \u00e0 1200 \u00b0C, permet de d\u00e9terminer le d\u00e9but de la combustion des gaz et vapeurs, et de pr\u00e9venir la surchauffe ainsi que l&#8217;endommagement de la structure.<br>&nbsp;<strong>c.<\/strong> La r\u00e9gulation de la quantit\u00e9 d&#8217;air dans le postcombusteur permet de maintenir des conditions optimales pour la postcombustion de l&#8217;exc\u00e8s de gaz et vapeurs, tout en minimisant les \u00e9missions nocives.<\/p>\n\n\n\n<p><strong>2. Ce qui est d\u00e9velopp\u00e9<br><\/strong>&nbsp;<strong>a.<\/strong> Des \u00e9l\u00e9ments structurels du foyer et du postcombusteur permettant un r\u00e9glage automatique de la quantit\u00e9 d&#8217;air pour la combustion et la postcombustion du gaz de pyrolyse dans le syst\u00e8me, en utilisant des \u00e9l\u00e9ments du SCA.<br>&nbsp;<strong>b.<\/strong> Un SCA pour le fonctionnement du syst\u00e8me de combustion et de postcombustion des gaz de pyrolyse, bas\u00e9 sur les signaux des capteurs de temp\u00e9rature et le contr\u00f4le des actionneurs de clapets d&#8217;air.<\/p>\n\n\n\n<p><strong>3. Exigences \u00e9tablies pour les clapets d&#8217;air r\u00e9glables<br><\/strong>&nbsp;<strong>a.<\/strong> Fixation rigide et fiable de l&#8217;actionneur au corps du clapet \u00e0 l&#8217;aide d&#8217;un kit de montage standard correspondant \u00e0 la taille de l&#8217;actionneur.<br>&nbsp;<strong>b.<\/strong> Compatibilit\u00e9 de l&#8217;arbre du clapet avec l&#8217;actionneur (en diam\u00e8tre et en forme) pour une transmission pr\u00e9cise de la rotation.<br>&nbsp;<strong>c.<\/strong> Possibilit\u00e9 de r\u00e9gler la position initiale du clapet.<br>&nbsp;<strong>d.<\/strong> Acc\u00e8s pratique et s\u00fbr pour l&#8217;entretien et le raccordement de l&#8217;actionneur \u00e9lectrique (c\u00e2bles d&#8217;alimentation et de r\u00e9troaction).<br>&nbsp;<strong>e.<\/strong> Un actionneur rotatif avec r\u00e9troaction est utilis\u00e9 comme entra\u00eenement \u00e9lectrique.<br>&nbsp;<strong>f.<\/strong> Possibilit\u00e9 d&#8217;utiliser un r\u00e9glage manuel du clapet lors du d\u00e9branchement de l&#8217;actionneur \u00e9lectrique du clapet d&#8217;air.<\/p>\n\n\n\n<p><strong>4. Effet obtenu<br><\/strong>&nbsp;<strong>a. Efficacit\u00e9 du processus.<\/strong> Augmentation de la stabilit\u00e9 et de l&#8217;efficacit\u00e9 de la combustion et de la postcombustion des gaz et vapeurs de pyrolyse, ce qui influence la productivit\u00e9 globale du four.<br>&nbsp;<strong>b. Protection contre la surchauffe.<\/strong> R\u00e9duction du risque de surchauffe et protection des \u00e9l\u00e9ments structurels gr\u00e2ce au contr\u00f4le des temp\u00e9ratures, ce qui diminue le risque d&#8217;arr\u00eats impr\u00e9vus du four.<br>&nbsp;<strong>c. Contr\u00f4le \u00e9cologique.<\/strong> Maintien du r\u00e9gime optimal de postcombustion pour minimiser les \u00e9missions nocives.<br>&nbsp;<strong>d. R\u00e9duction du facteur humain.<\/strong> Augmentation de l&#8217;automatisation du processus et du confort de travail de l&#8217;op\u00e9rateur gr\u00e2ce au SCA et au syst\u00e8me d&#8217;alerte.<\/p>\n\n\n\n<p>Pour toute question relative \u00e0 la mise en \u0153uvre de ce syst\u00e8me d&#8217;automatisation, y compris la modernisation des \u00e9quipements actuels, nous vous prions de nous contacter via les formulaires de contact du site web.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GreenPower poursuit la modernisation du syst\u00e8me de contr\u00f4le automatique (SCA) du four de pyrolyse EKKO-2. L&#8217;objectif principal de la mise en \u0153uvre du SCA est de r\u00e9duire le niveau d&#8217;intervention du personnel dans l&#8217;exploitation du four, afin d&#8217;optimiser le processus de contr\u00f4le, de minimiser le facteur humain et d&#8217;accro\u00eetre la stabilit\u00e9 des processus de production.<\/p>\n","protected":false},"author":4,"featured_media":15465,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[],"class_list":["post-15491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Modernisation de l&#039;EKKO-2: d\u00e9veloppement de clapets d&#039;air r\u00e9glables pour le foyer et le postcombusteur - Greenpower<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modernisation de l&#039;EKKO-2: d\u00e9veloppement de clapets d&#039;air r\u00e9glables pour le foyer et le postcombusteur - Greenpower\" \/>\n<meta property=\"og:description\" content=\"GreenPower poursuit la modernisation du syst\u00e8me de contr\u00f4le automatique (SCA) du four de pyrolyse EKKO-2. L&#8217;objectif principal de la mise en \u0153uvre du SCA est de r\u00e9duire le niveau d&#8217;intervention du personnel dans l&#8217;exploitation du four, afin d&#8217;optimiser le processus de contr\u00f4le, de minimiser le facteur humain et d&#8217;accro\u00eetre la stabilit\u00e9 des processus de production.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/\" \/>\n<meta property=\"og:site_name\" content=\"Greenpower\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-18T10:36:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greenpower.webidev.de\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"951\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u043e\u0436\u043a\u043e\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u043e\u0436\u043a\u043e\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/\"},\"author\":{\"name\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u043e\u0436\u043a\u043e\",\"@id\":\"https:\/\/greenpower.equipment\/#\/schema\/person\/4dca2406f70a187cbbd8d64bd3bb1788\"},\"headline\":\"Modernisation de l&#8217;EKKO-2: d\u00e9veloppement de clapets d&#8217;air r\u00e9glables pour le foyer et le postcombusteur\",\"datePublished\":\"2026-02-18T10:36:20+00:00\",\"dateModified\":\"2026-02-18T10:36:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/\"},\"wordCount\":669,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/greenpower.equipment\/#organization\"},\"image\":{\"@id\":\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/\",\"url\":\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/\",\"name\":\"Modernisation de l'EKKO-2: d\u00e9veloppement de clapets d'air r\u00e9glables pour le foyer et le postcombusteur - Greenpower\",\"isPartOf\":{\"@id\":\"https:\/\/greenpower.equipment\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193.jpg\",\"datePublished\":\"2026-02-18T10:36:20+00:00\",\"dateModified\":\"2026-02-18T10:36:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#primaryimage\",\"url\":\"https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193.jpg\",\"contentUrl\":\"https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193.jpg\",\"width\":1280,\"height\":951},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\/\/greenpower.equipment\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modernisation de l&#8217;EKKO-2: d\u00e9veloppement de clapets d&#8217;air r\u00e9glables pour le foyer et le postcombusteur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/greenpower.equipment\/#website\",\"url\":\"https:\/\/greenpower.equipment\/\",\"name\":\"Greenpower\",\"description\":\"We focus on the development of technologies for processing various kinds of waste into useful products that are in demand on the market, creating eco-friendly equipment with an optimal price-performance-quality ratio.\",\"publisher\":{\"@id\":\"https:\/\/greenpower.equipment\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/greenpower.equipment\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/greenpower.equipment\/#organization\",\"name\":\"Greenpower\",\"url\":\"https:\/\/greenpower.equipment\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/greenpower.equipment\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/greenpower.equipment\/wp-content\/uploads\/2024\/11\/cropped-GreenPower_logo-1.png\",\"contentUrl\":\"https:\/\/greenpower.equipment\/wp-content\/uploads\/2024\/11\/cropped-GreenPower_logo-1.png\",\"width\":1500,\"height\":1500,\"caption\":\"Greenpower\"},\"image\":{\"@id\":\"https:\/\/greenpower.equipment\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/greenpower.equipment\/#\/schema\/person\/4dca2406f70a187cbbd8d64bd3bb1788\",\"name\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u043e\u0436\u043a\u043e\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/greenpower.equipment\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/410dd73bc6857413f15a6bc74ab093d55d0faf39f187ef7473a9c71950eaa2af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/410dd73bc6857413f15a6bc74ab093d55d0faf39f187ef7473a9c71950eaa2af?s=96&d=mm&r=g\",\"caption\":\"\u041e\u043a\u0441\u0430\u043d\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u043e\u0436\u043a\u043e\"},\"url\":\"https:\/\/greenpower.equipment\/fr\/author\/koksik\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modernisation de l'EKKO-2: d\u00e9veloppement de clapets d'air r\u00e9glables pour le foyer et le postcombusteur - Greenpower","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/","og_locale":"fr_FR","og_type":"article","og_title":"Modernisation de l'EKKO-2: d\u00e9veloppement de clapets d'air r\u00e9glables pour le foyer et le postcombusteur - Greenpower","og_description":"GreenPower poursuit la modernisation du syst\u00e8me de contr\u00f4le automatique (SCA) du four de pyrolyse EKKO-2. L&#8217;objectif principal de la mise en \u0153uvre du SCA est de r\u00e9duire le niveau d&#8217;intervention du personnel dans l&#8217;exploitation du four, afin d&#8217;optimiser le processus de contr\u00f4le, de minimiser le facteur humain et d&#8217;accro\u00eetre la stabilit\u00e9 des processus de production.","og_url":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/","og_site_name":"Greenpower","article_published_time":"2026-02-18T10:36:20+00:00","og_image":[{"width":1280,"height":951,"url":"https:\/\/greenpower.webidev.de\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193.jpg","type":"image\/jpeg"}],"author":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u043e\u0436\u043a\u043e","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u043e\u0436\u043a\u043e","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#article","isPartOf":{"@id":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/"},"author":{"name":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u043e\u0436\u043a\u043e","@id":"https:\/\/greenpower.equipment\/#\/schema\/person\/4dca2406f70a187cbbd8d64bd3bb1788"},"headline":"Modernisation de l&#8217;EKKO-2: d\u00e9veloppement de clapets d&#8217;air r\u00e9glables pour le foyer et le postcombusteur","datePublished":"2026-02-18T10:36:20+00:00","dateModified":"2026-02-18T10:36:20+00:00","mainEntityOfPage":{"@id":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/"},"wordCount":669,"commentCount":0,"publisher":{"@id":"https:\/\/greenpower.equipment\/#organization"},"image":{"@id":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#primaryimage"},"thumbnailUrl":"https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/","url":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/","name":"Modernisation de l'EKKO-2: d\u00e9veloppement de clapets d'air r\u00e9glables pour le foyer et le postcombusteur - Greenpower","isPartOf":{"@id":"https:\/\/greenpower.equipment\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#primaryimage"},"image":{"@id":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#primaryimage"},"thumbnailUrl":"https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193.jpg","datePublished":"2026-02-18T10:36:20+00:00","dateModified":"2026-02-18T10:36:20+00:00","breadcrumb":{"@id":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#primaryimage","url":"https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193.jpg","contentUrl":"https:\/\/greenpower.equipment\/wp-content\/uploads\/2026\/02\/\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2026-02-18_12-04-01-193.jpg","width":1280,"height":951},{"@type":"BreadcrumbList","@id":"https:\/\/greenpower.equipment\/fr\/modernisation-de-lekko-2-developpement-de-clapets-dair-reglables-pour-le-foyer-et-le-postcombusteur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/greenpower.equipment\/fr\/"},{"@type":"ListItem","position":2,"name":"Modernisation de l&#8217;EKKO-2: d\u00e9veloppement de clapets d&#8217;air r\u00e9glables pour le foyer et le postcombusteur"}]},{"@type":"WebSite","@id":"https:\/\/greenpower.equipment\/#website","url":"https:\/\/greenpower.equipment\/","name":"Greenpower","description":"We focus on the development of technologies for processing various kinds of waste into useful products that are in demand on the market, creating eco-friendly equipment with an optimal price-performance-quality ratio.","publisher":{"@id":"https:\/\/greenpower.equipment\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greenpower.equipment\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/greenpower.equipment\/#organization","name":"Greenpower","url":"https:\/\/greenpower.equipment\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/greenpower.equipment\/#\/schema\/logo\/image\/","url":"https:\/\/greenpower.equipment\/wp-content\/uploads\/2024\/11\/cropped-GreenPower_logo-1.png","contentUrl":"https:\/\/greenpower.equipment\/wp-content\/uploads\/2024\/11\/cropped-GreenPower_logo-1.png","width":1500,"height":1500,"caption":"Greenpower"},"image":{"@id":"https:\/\/greenpower.equipment\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/greenpower.equipment\/#\/schema\/person\/4dca2406f70a187cbbd8d64bd3bb1788","name":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u043e\u0436\u043a\u043e","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/greenpower.equipment\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/410dd73bc6857413f15a6bc74ab093d55d0faf39f187ef7473a9c71950eaa2af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/410dd73bc6857413f15a6bc74ab093d55d0faf39f187ef7473a9c71950eaa2af?s=96&d=mm&r=g","caption":"\u041e\u043a\u0441\u0430\u043d\u0430 \u0413\u0440\u0435\u0431\u0435\u043d\u043e\u0436\u043a\u043e"},"url":"https:\/\/greenpower.equipment\/fr\/author\/koksik\/"}]}},"_links":{"self":[{"href":"https:\/\/greenpower.equipment\/fr\/wp-json\/wp\/v2\/posts\/15491\/"}],"collection":[{"href":"https:\/\/greenpower.equipment\/fr\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/greenpower.equipment\/fr\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/greenpower.equipment\/fr\/wp-json\/wp\/v2\/users\/4\/"}],"replies":[{"embeddable":true,"href":"https:\/\/greenpower.equipment\/fr\/wp-json\/wp\/v2\/comments\/?post=15491"}],"version-history":[{"count":1,"href":"https:\/\/greenpower.equipment\/fr\/wp-json\/wp\/v2\/posts\/15491\/revisions\/"}],"predecessor-version":[{"id":15492,"href":"https:\/\/greenpower.equipment\/fr\/wp-json\/wp\/v2\/posts\/15491\/revisions\/15492\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greenpower.equipment\/fr\/wp-json\/wp\/v2\/media\/15465\/"}],"wp:attachment":[{"href":"https:\/\/greenpower.equipment\/fr\/wp-json\/wp\/v2\/media\/?parent=15491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greenpower.equipment\/fr\/wp-json\/wp\/v2\/categories\/?post=15491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greenpower.equipment\/fr\/wp-json\/wp\/v2\/tags\/?post=15491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}